{"id":2836,"date":"2024-10-12T21:47:22","date_gmt":"2024-10-12T18:47:22","guid":{"rendered":"https:\/\/www.dentaglobal.com\/hizmetler\/gummy-smile-treatment\/"},"modified":"2024-10-15T14:41:54","modified_gmt":"2024-10-15T11:41:54","slug":"gummy-smile-behandlung","status":"publish","type":"hizmetler","link":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/","title":{"rendered":"Gummy Smile Behandlung"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Gummy Smile Behandlung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df an Zahnfleisch in ihrem L\u00e4cheln ihr Aussehen beeintr\u00e4chtigt. Experten in der Zahnheilkunde, bieten Behandlungen zur Beseitigung von Zahnstein, aber auch Zahnfleischoperationen, Lappenoperationen und Papillenoperationen sowie Tiefenk\u00fcrettage an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um \u00fcberm\u00e4\u00dfig gummiartiges L\u00e4cheln zu vermeiden, k\u00f6nnen Parodontologen das Zahnfleisch durch Gingivektomien und Gingivoplastiken nach Wunsch formen.<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\">What Should Healthy Gums Look Like?<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wie sollte gesundes Zahnfleisch aussehen?<\/li>\n\n\n\n<li>Hellrosa mit dem Aussehen von Orangenhaut.<\/li>\n\n\n\n<li>Ein gleichm\u00e4\u00dfiger Zahnfleischrand, der die Z\u00e4hne von der Wurzel her abdeckt;<\/li>\n\n\n\n<li>Keine \u00fcberm\u00e4\u00dfige R\u00f6tung, Schwellung oder Infektion;<\/li>\n\n\n\n<li>Keine Blutungen beim Z\u00e4hneputzen oder Zahnseide;<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_235144528-750x500-1.jpg\" alt=\"\" class=\"wp-image-1795 size-full\" srcset=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_235144528-750x500-1.jpg 750w, https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_235144528-750x500-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_644956462-750x500-1.jpg\" alt=\"\" class=\"wp-image-1800 size-full\" srcset=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_644956462-750x500-1.jpg 750w, https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_644956462-750x500-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading has-text-align-right\">Gr\u00fcnde f\u00fcr Zahnfleischerkrankungen:<\/h3>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Der Hauptgrund f\u00fcr Zahnfleischerkrankungen ist entweder bakterieller Zahnbelag oder \u201emikrobieller Zahnbelag\u201c\u2013 eine klebrige, transparente Schicht, die fest an den Z\u00e4hnen haftet und durch unwirksames und unregelm\u00e4\u00dfiges Z\u00e4hneputzen entsteht. Da es die gleiche Farbe wie der Zahn hat, ist es mit blo\u00dfem Auge schwer zu erkennen. Plaque ist weich und kann leicht mit einer Zahnb\u00fcrste und Zahnseide entfernt werden. Wird das Plaque jedoch nicht rechtzeitig entfernt, verkalkt, verh\u00e4rtet und verursacht Zahnstein. Die raue Struktur von Zahnstein f\u00fchrt dazu, dass sich Plaque \u2013 wie auch Infektionen \u2013 schneller ansammeln.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\">Andere Gr\u00fcnde f\u00fcr Zahnfleischerkrankungen:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Rauchen ist \u00e4u\u00dferst sch\u00e4dlich f\u00fcr die Mundschleimhaut und das Zahnfleisch, macht letzteres weicher und \u00f6ffnet den Weg f\u00fcr Zahnfleischerkrankungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Wissenschaftlern ist die genetische Ausstattung auch zu 30 % f\u00fcr Zahnfleischerkrankungen verantwortlich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Zeiten, in denen die hormonellen Ver\u00e4nderungen durch Schwangerschaft, Pubert\u00e4t, Wechseljahre und Menstruation am intensivsten sind, muss der Mundhygiene mehr Aufmerksamkeit geschenkt werden, da das Zahnfleisch in diesen Zeiten empfindlicher ist.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_326188592-750x500-1.jpg\" alt=\"\" class=\"wp-image-1805 size-full\" srcset=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_326188592-750x500-1.jpg 750w, https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/shutterstock_326188592-750x500-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Studien haben auch gezeigt, dass Stress die Abwehrkr\u00e4fte des K\u00f6rpers verringert, was sich auch auf die Entstehung von Parodontalerkrankungen auswirkt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die Einnahme von Medikamenten, Antibabypillen, Antidepressiva und Herztabletten beeintr\u00e4chtigt die Mundgesundheit und kann eine besondere Aufmerksamkeit bei der Zahnpflege erforderlich machen. Wenn Sie solche Medikamente einnehmen, informieren Sie bitte vor der Behandlung Ihren Zahnarzt. Auch das Z\u00e4hneknirschen f\u00fchrt zu einer Sch\u00e4digung des Zahnhalteapparates.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Menschen mit Diabetes haben ein hohes Risiko, parodontale (gingivale) Infektionen zu entwickeln und sollten regelm\u00e4\u00dfig von einem Parodontologen untersucht werden und gleichzeitig auf ihre Mundhygiene achten. Au\u00dferdem f\u00fchrt eine mangelnde Ern\u00e4hrung zu einem schwachen Immunsystem, das die k\u00f6rpereigene F\u00e4higkeit, Infektionen, einschlie\u00dflich Zahnfleischinfektionen, abzuwehren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch F\u00fcllungen, Kronen und Br\u00fccken, die falsch gegen das Zahnfleisch dr\u00fccken, k\u00f6nnen Probleme verursachen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Um ein gesundes Zahnfleisch zu gew\u00e4hrleisten:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Putzen Sie Ihre Z\u00e4hne jeden Tag richtig und verwenden Sie Zahnseide<\/li>\n\n\n\n<li>Ern\u00e4hren Sie sich ausgewogen, vermeiden Sie unn\u00f6tige Kalorien und vermeiden Sie Lebensmittel, die an Ihren Z\u00e4hnen kleben bleiben.<\/li>\n\n\n\n<li>Untersuchen Sie Ihre Z\u00e4hne regelm\u00e4\u00dfig, um die ersten Anzeichen einer oralen oder dentalen Ver\u00e4nderung zu erkennen.<\/li>\n\n\n\n<li>Gehen Sie mindestens zweimal im Jahr zum Zahnarzt, um Zahnsteinablagerungen zu entfernen.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Der n\u00e4chste Schritt<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der n\u00e4chste Schritt ist die Vereinbarung eines Beratungsgespr\u00e4chs mit einer der DENTAGLOBAL angeschlossenen Agenturen in Paris, London, Rotterdam oder unserer eigenen Zahnklinik in Izmir. Eine deutschsprachige Beratung kann Ihnen zur Verf\u00fcgung gestellt werden. Gerne senden wir Ihnen ein Angebot,&nbsp; hierf\u00fcr f\u00fcllen Sie bitte das detaillierte Formular auf unserer Webseite aus. Wir freuen uns auf Ihren Anruf<\/p>\n","protected":false},"excerpt":{"rendered":"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df an Zahnfleisch in ihrem L\u00e4cheln ihr Aussehen beeintr\u00e4chtigt. Experten in der Zahnheilkunde, bieten Behandlungen zur Beseitigung von Zahnstein, aber auch Zahnfleischoperationen, Lappenoperationen und Papillenoperationen sowie Tiefenk\u00fcrettage an. Um \u00fcberm\u00e4\u00dfig gummiartiges L\u00e4cheln zu [&hellip;]","protected":false},"featured_media":1813,"template":"","class_list":["post-2836","hizmetler","type-hizmetler","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gummy Smile Behandlung - Dentaglobal<\/title>\n<meta name=\"description\" content=\"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gummy Smile Behandlung - Dentaglobal\" \/>\n<meta property=\"og:description\" content=\"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/\" \/>\n<meta property=\"og:site_name\" content=\"Dentaglobal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dentaglobal\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T11:41:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/gummy-smile-treatment_373ac.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"314\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/\",\"url\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/\",\"name\":\"Gummy Smile Behandlung - Dentaglobal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dentaglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gummy-smile-treatment_373ac.jpg\",\"datePublished\":\"2024-10-12T18:47:22+00:00\",\"dateModified\":\"2024-10-15T11:41:54+00:00\",\"description\":\"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dentaglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gummy-smile-treatment_373ac.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dentaglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gummy-smile-treatment_373ac.jpg\",\"width\":314,\"height\":245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/hizmetler\\\/gummy-smile-behandlung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gummy Smile Behandlung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/\",\"name\":\"Dentaglobal Dental Clinic\",\"description\":\"Everyone Smiles in Same Language\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/#organization\",\"name\":\"Dentaglobal Dental Clinic\",\"url\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dentaglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-en.png\",\"contentUrl\":\"https:\\\/\\\/www.dentaglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-en.png\",\"width\":343,\"height\":73,\"caption\":\"Dentaglobal Dental Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dentaglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dentaglobal\",\"https:\\\/\\\/www.instagram.com\\\/dentaglobal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCTIlJImKSlGyEHsrNxcosVQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gummy Smile Behandlung - Dentaglobal","description":"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/","og_locale":"de_DE","og_type":"article","og_title":"Gummy Smile Behandlung - Dentaglobal","og_description":"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df","og_url":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/","og_site_name":"Dentaglobal","article_publisher":"https:\/\/www.facebook.com\/dentaglobal","article_modified_time":"2024-10-15T11:41:54+00:00","og_image":[{"width":314,"height":245,"url":"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/gummy-smile-treatment_373ac.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/","url":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/","name":"Gummy Smile Behandlung - Dentaglobal","isPartOf":{"@id":"https:\/\/www.dentaglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/#primaryimage"},"image":{"@id":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/gummy-smile-treatment_373ac.jpg","datePublished":"2024-10-12T18:47:22+00:00","dateModified":"2024-10-15T11:41:54+00:00","description":"Gummy Smile Behandlung Die Gummy Smile Behandlung ist in den letzten Jahren popul\u00e4r geworden, da sich viele Menschen dar\u00fcber beschweren, dass ein \u00dcberma\u00df","breadcrumb":{"@id":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/#primaryimage","url":"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/gummy-smile-treatment_373ac.jpg","contentUrl":"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/gummy-smile-treatment_373ac.jpg","width":314,"height":245},{"@type":"BreadcrumbList","@id":"https:\/\/www.dentaglobal.com\/de\/hizmetler\/gummy-smile-behandlung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/www.dentaglobal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gummy Smile Behandlung"}]},{"@type":"WebSite","@id":"https:\/\/www.dentaglobal.com\/de\/#website","url":"https:\/\/www.dentaglobal.com\/de\/","name":"Dentaglobal Dental Clinic","description":"Everyone Smiles in Same Language","publisher":{"@id":"https:\/\/www.dentaglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dentaglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.dentaglobal.com\/de\/#organization","name":"Dentaglobal Dental Clinic","url":"https:\/\/www.dentaglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.dentaglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/logo-en.png","contentUrl":"https:\/\/www.dentaglobal.com\/wp-content\/uploads\/2024\/10\/logo-en.png","width":343,"height":73,"caption":"Dentaglobal Dental Clinic"},"image":{"@id":"https:\/\/www.dentaglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dentaglobal","https:\/\/www.instagram.com\/dentaglobal\/","https:\/\/www.youtube.com\/channel\/UCTIlJImKSlGyEHsrNxcosVQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.dentaglobal.com\/de\/wp-json\/wp\/v2\/hizmetler\/2836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dentaglobal.com\/de\/wp-json\/wp\/v2\/hizmetler"}],"about":[{"href":"https:\/\/www.dentaglobal.com\/de\/wp-json\/wp\/v2\/types\/hizmetler"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dentaglobal.com\/de\/wp-json\/wp\/v2\/media\/1813"}],"wp:attachment":[{"href":"https:\/\/www.dentaglobal.com\/de\/wp-json\/wp\/v2\/media?parent=2836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}